{"id":3855,"date":"2022-04-21T14:25:28","date_gmt":"2022-04-21T12:25:28","guid":{"rendered":"https:\/\/blog.rivieraholidayhomes.com\/?p=3855"},"modified":"2022-04-21T15:01:27","modified_gmt":"2022-04-21T13:01:27","slug":"7-choses-passionnantes-a-decouvrir-a-vence","status":"publish","type":"post","link":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/","title":{"rendered":"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence"},"content":{"rendered":"\n<p class=\"p1\">Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles d\u2019histoire, vous attend tranquillement, juch\u00e9e au pied du col de Vence, entre vall\u00e9e et montagne. Faites comme Matisse, Dufy, Chagall\u2026.prenez le temps de venir la contempler, vous ne le regretterez pas.<\/p>\n\n\n\n<p class=\"p1\">Voici quelques \u00ab&nbsp;perles de Vence&nbsp;\u00bb \u00e0 admirer :<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>La vieille ville de Vence <\/b>: <\/h2>\n\n\n\n<p>Au sein de ses remparts du XIIIe si\u00e8cle en forme d\u2019ellipse, l\u2019antique ville de Vence, rassembl\u00e9e \u00e0 l\u2019ombre des hauts murs de pierre, serre autour de ses jolies placettes des maisons qui ont vu des si\u00e8cles d\u00e9filer. Y fl\u00e2ner est un bonheur, tant elle rassemble d\u2019artisans d\u2019art, de galeries et de petits restaurants de charme.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/vence.fr\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/vieille-ville-de-vence-1200x630.jpg\" alt=\"\" class=\"wp-image-3861\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><b>La cath\u00e9drale la plus petite de France : <\/b><\/h2>\n\n\n\n<p>Dissimul\u00e9e derri\u00e8re son porche color\u00e9, parfaite illustration du baroque ligure, la cath\u00e9drale Notre Dame d\u00e9voile son int\u00e9rieur plein d\u2019ombre, comme il sied en pays m\u00e9diterran\u00e9en. Une visite \u00e0 l\u2019\u00e9tage vous permettra de voir la statuaire en bois polychrome du XVIe au XVIIIe si\u00e8cle, d\u2019une expressivit\u00e9 remarquable. Les artistes nous ont l\u00e9gu\u00e9 l\u00e0 un ensemble d\u2019oeuvres tr\u00e8s \u00e9mouvantes, pleines de spiritualit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Le grand Fr\u00eane de Vence<\/b> , <\/h2>\n\n\n\n<p>Un arbre remarquable plant\u00e9 au XVIe, et qui continue chaque printemps \u00e0 \u00e9tonner les ven\u00e7ois par sa r\u00e9silience, t\u00e9moin verdoyant des si\u00e8cles pass\u00e9s. Il m\u00e9rite au passage votre salut, cet anc\u00eatre v\u00e9g\u00e9tal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>L\u2019Office du Tourisme et l\u2019espace Gombrowicz : <\/b><\/h2>\n\n\n\n<p>L\u2019office est log\u00e9 dans une demeure sublime, la Villa Alexandrine, construite en 1911, en pleine Belle Epoque. Elle a \u00e9t\u00e9 r\u00e9nov\u00e9e, ses fresques d\u2019\u00e9poque conserv\u00e9es et nettoy\u00e9es. C\u2019est un endroit magnifique, avec de plus des conseillers d\u2019une rare gentillesse. A l\u2019\u00e9tage, d\u00e9couvrez aussi l\u2019espace du c\u00e9l\u00e8bre philosophe polonais, qui a pass\u00e9 la fin de sa vie \u00e0 Vence, dans cette villa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>D\u00e9couvrez l\u2019<a href=\"https:\/\/latelierfrancais.net\/fr\/\" target=\"_blank\" aria-label=\"undefined (s\u2019ouvre dans un nouvel onglet)\" rel=\"noreferrer noopener\">Atelier Fran\u00e7ais<\/a> : <\/b><\/h2>\n\n\n\n<p>Cette tr\u00e8s jolie boutique, assortie d\u2019un salon de th\u00e9 face au mus\u00e9e d\u2019art contemporain de Vence d\u00e9veloppe un concept 100% Made in France.\u00a0 D\u00e9coration contemporaine et raffin\u00e9e, mode vraiment dans la tendance, bar \u00e0 bijoux fascinant, jouets aussi intelligents que charmants\u2026 La sympathique propri\u00e9taire de ce concept store vous accueille avec le sourire en prime.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/latelierfrancais.net\/fr\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/atelier-franc\u0327ais-1200x630.jpg\" alt=\"\" class=\"wp-image-3865\"\/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><b>Un d\u00e9jeuner ou une glace \u00e0 la R\u00e9gence, <\/b><\/h2>\n\n\n\n<p>Place du grand jardin. Cette brasserie en a vu passer des artistes, au cours des apr\u00e8s-midi d\u2019\u00e9t\u00e9, sur sa belle terrasse ensoleill\u00e9e ! Sa carte \u00e0 la fois m\u00e9diterran\u00e9enne et de grande qualit\u00e9 lui assure une r\u00e9putation sans faille. Lieu central de la vie ven\u00e7oise, entour\u00e9 de restaurants et de bars tout aussi conviviaux, la R\u00e9gence est une invitation \u00e0 un certain art de vivre d\u00e9contract\u00e9 et sans esbroufe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><b>La chapelle Matisse, ou <a href=\"http:\/\/chapellematisse.com\/\" target=\"_blank\" aria-label=\"undefined (s\u2019ouvre dans un nouvel onglet)\" rel=\"noreferrer noopener\">Chapelle du Rosaire<\/a>, <\/b><\/h2>\n\n\n\n<p class=\"p1\">Cette chapelle \u00e9t\u00e9 \u00e9rig\u00e9e et d\u00e9cor\u00e9e entre 1949 et 1951 sous l\u2019\u00e9gide de l\u2019artiste lui-m\u00eame. Amateurs d\u2019art baroque ou de compositions sophistiqu\u00e9es, passez votre chemin, car elle est d\u2019une simplicit\u00e9 exemplaire. A l\u2019int\u00e9rieur, le jeu de la lumi\u00e8re \u00e0 travers les \u00e9troits vitraux bleus, verts, rouges\u2026 vient enchanter la quasi-aust\u00e9rit\u00e9 d\u2019un endroit pur, radicalement con\u00e7u pour la pri\u00e8re.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/chapelle-du-rosaire-vence-1200x630.jpg\" alt=\"\" class=\"wp-image-3868\"\/><\/figure>\n\n\n\n<p class=\"p1\">Vence, dit-on, est la ville ch\u00e9rie de touristes qui y reviennent chaque \u00e9t\u00e9. Loin de tohu-bohu de la c\u00f4te (et pourtant si proche), elle s\u00e9duit par sa \u00ab\u00a0dolce vita\u00a0\u00bb raffin\u00e9e, et pourtant authentique. Il ne faut pas manquer tant de beaut\u00e9, mais aussi tant de vie chaleureuse group\u00e9e autour des remparts en ellipse de sa vieille ville.<\/p>\n\n\n\n<p>Lire aussi > <a href=\"https:\/\/blog.rivieraholidayhomes.com\/fr\/10-choses-merveilleuses-faire-villefranche-sur-mer\/\" target=\"_blank\" aria-label=\"undefined (s\u2019ouvre dans un nouvel onglet)\" rel=\"noreferrer noopener\">10 choses merveilleuses \u00e0 faire \u00e0 Villefranche sur Mer<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte&#8230;<\/p>\n","protected":false},"author":3,"featured_media":3858,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,8,17],"tags":[],"class_list":["post-3855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-savoir","category-activites","category-vacances"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence - Blog<\/title>\n<meta name=\"description\" content=\"Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence - Blog\" \/>\n<meta property=\"og:description\" content=\"Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-21T12:25:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-21T13:01:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentin Giulian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentin Giulian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/\"},\"author\":{\"name\":\"Valentin Giulian\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/#\\\/schema\\\/person\\\/7f3445cffdfbd06292e476040ddfd6d7\"},\"headline\":\"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence\",\"datePublished\":\"2022-04-21T12:25:28+00:00\",\"dateModified\":\"2022-04-21T13:01:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/\"},\"wordCount\":654,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg\",\"articleSection\":[\"\u00c0 savoir\",\"Activit\u00e9s\",\"Vacances\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/\",\"url\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/\",\"name\":\"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg\",\"datePublished\":\"2022-04-21T12:25:28+00:00\",\"dateModified\":\"2022-04-21T13:01:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/#\\\/schema\\\/person\\\/7f3445cffdfbd06292e476040ddfd6d7\"},\"description\":\"Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg\",\"width\":360,\"height\":240,\"caption\":\"Vue ar\u00e9rienne de Vence avec en fond la m\u00e8re m\u00e9dit\u00e9rann\u00e9e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/7-choses-passionnantes-a-decouvrir-a-vence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/#website\",\"url\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/\",\"name\":\"Blog\",\"description\":\"Riviera Holiday Homes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/#\\\/schema\\\/person\\\/7f3445cffdfbd06292e476040ddfd6d7\",\"name\":\"Valentin Giulian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd61c38938932b1b843f073f9a7ff960f0f81c0a170eebb1d353562c0bbcaf71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd61c38938932b1b843f073f9a7ff960f0f81c0a170eebb1d353562c0bbcaf71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fd61c38938932b1b843f073f9a7ff960f0f81c0a170eebb1d353562c0bbcaf71?s=96&d=mm&r=g\",\"caption\":\"Valentin Giulian\"},\"url\":\"https:\\\/\\\/blog.rivieraholidayhomes.com\\\/fr\\\/author\\\/valentin-giulian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence - Blog","description":"Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/","og_locale":"fr_FR","og_type":"article","og_title":"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence - Blog","og_description":"Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles","og_url":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/","og_site_name":"Blog","article_published_time":"2022-04-21T12:25:28+00:00","article_modified_time":"2022-04-21T13:01:27+00:00","og_image":[{"width":360,"height":240,"url":"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg","type":"image\/jpeg"}],"author":"Valentin Giulian","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Valentin Giulian","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#article","isPartOf":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/"},"author":{"name":"Valentin Giulian","@id":"https:\/\/blog.rivieraholidayhomes.com\/#\/schema\/person\/7f3445cffdfbd06292e476040ddfd6d7"},"headline":"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence","datePublished":"2022-04-21T12:25:28+00:00","dateModified":"2022-04-21T13:01:27+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/"},"wordCount":654,"commentCount":0,"image":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg","articleSection":["\u00c0 savoir","Activit\u00e9s","Vacances"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/","url":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/","name":"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence - Blog","isPartOf":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#primaryimage"},"image":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg","datePublished":"2022-04-21T12:25:28+00:00","dateModified":"2022-04-21T13:01:27+00:00","author":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/#\/schema\/person\/7f3445cffdfbd06292e476040ddfd6d7"},"description":"Derri\u00e8re la C\u00f4te d\u2019Azur, un fabuleux arri\u00e8re-pays vous attend. Amoureux d\u2019histoire, d\u2019art et de patrimoine, la ville de Vence, forte de plus de 20 si\u00e8cles","breadcrumb":{"@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#primaryimage","url":"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg","contentUrl":"https:\/\/blog.rivieraholidayhomes.com\/wp-content\/uploads\/2022\/04\/riviera-holiday-homes-vence-view-mediteranne\u0301e.jpg","width":360,"height":240,"caption":"Vue ar\u00e9rienne de Vence avec en fond la m\u00e8re m\u00e9dit\u00e9rann\u00e9e"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.rivieraholidayhomes.com\/fr\/7-choses-passionnantes-a-decouvrir-a-vence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.rivieraholidayhomes.com\/"},{"@type":"ListItem","position":2,"name":"7 choses passionnantes \u00e0 d\u00e9couvrir \u00e0 Vence"}]},{"@type":"WebSite","@id":"https:\/\/blog.rivieraholidayhomes.com\/#website","url":"https:\/\/blog.rivieraholidayhomes.com\/","name":"Blog","description":"Riviera Holiday Homes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.rivieraholidayhomes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.rivieraholidayhomes.com\/#\/schema\/person\/7f3445cffdfbd06292e476040ddfd6d7","name":"Valentin Giulian","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/fd61c38938932b1b843f073f9a7ff960f0f81c0a170eebb1d353562c0bbcaf71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fd61c38938932b1b843f073f9a7ff960f0f81c0a170eebb1d353562c0bbcaf71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd61c38938932b1b843f073f9a7ff960f0f81c0a170eebb1d353562c0bbcaf71?s=96&d=mm&r=g","caption":"Valentin Giulian"},"url":"https:\/\/blog.rivieraholidayhomes.com\/fr\/author\/valentin-giulian\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/posts\/3855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/comments?post=3855"}],"version-history":[{"count":4,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/posts\/3855\/revisions"}],"predecessor-version":[{"id":3873,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/posts\/3855\/revisions\/3873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/media\/3858"}],"wp:attachment":[{"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/media?parent=3855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/categories?post=3855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.rivieraholidayhomes.com\/fr\/wp-json\/wp\/v2\/tags?post=3855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}